{"id":8615,"date":"2023-03-16T18:12:11","date_gmt":"2023-03-16T16:12:11","guid":{"rendered":"https:\/\/thegoodmood.com\/?page_id=8615"},"modified":"2025-03-20T17:48:43","modified_gmt":"2025-03-20T15:48:43","slug":"4-estrellas","status":"publish","type":"page","link":"https:\/\/thegoodmood.com\/eng\/4-estrellas\/","title":{"rendered":"4 Estrellas"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"8615\" class=\"elementor elementor-8615\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-139d530 elementor-section-stretched elementor-section-full_width elementor-section-height-full elementor-hidden-tablet elementor-hidden-phone elementor-section-height-default elementor-section-items-middle\" data-id=\"139d530\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;90fbb8a&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}],&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_start&quot;:4,&quot;background_video_link&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=xPHcxcZKIKA&quot;}\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-background-video-container elementor-hidden-phone\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-background-video-embed\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-03a4346 animated-fast\" data-id=\"03a4346\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1e02151 elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"1e02151\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;652b578&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b3fbff4\" data-id=\"b3fbff4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4a5b626 animated-slow elementor-invisible\" data-id=\"4a5b626\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:3000}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"jet-parallax-widget elementor-element elementor-element-f9ced96 elementor-widget elementor-widget-image\" data-jet-tricks-settings=\"{&quot;parallax&quot;:&quot;true&quot;,&quot;invert&quot;:&quot;false&quot;,&quot;speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:100,&quot;sizes&quot;:[]},&quot;stickyOn&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}\" data-id=\"f9ced96\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2048\" height=\"716\" src=\"https:\/\/thegoodmood.com\/wp-content\/uploads\/2023\/04\/4estrellas_logo_4K_invert-2048x716.png\" class=\"attachment-2048x2048 size-2048x2048 wp-image-8708\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/thegoodmood.com\/wp-content\/uploads\/2023\/04\/4estrellas_logo_4K_invert-2048x716.png 2048w, https:\/\/thegoodmood.com\/wp-content\/uploads\/2023\/04\/4estrellas_logo_4K_invert-300x105.png 300w, https:\/\/thegoodmood.com\/wp-content\/uploads\/2023\/04\/4estrellas_logo_4K_invert-1024x358.png 1024w, https:\/\/thegoodmood.com\/wp-content\/uploads\/2023\/04\/4estrellas_logo_4K_invert-768x269.png 768w, https:\/\/thegoodmood.com\/wp-content\/uploads\/2023\/04\/4estrellas_logo_4K_invert-1536x537.png 1536w, https:\/\/thegoodmood.com\/wp-content\/uploads\/2023\/04\/4estrellas_logo_4K_invert-18x6.png 18w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-8f2c87a\" data-id=\"8f2c87a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b5e19b elementor-widget elementor-widget-spacer\" data-id=\"0b5e19b\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6b150e8 elementor-section-full_width elementor-section-content-bottom elementor-section-height-default elementor-section-height-default\" data-id=\"6b150e8\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;652b578&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-51c9086 animated-slow elementor-invisible\" data-id=\"51c9086\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:1000}\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-43aacfe\" data-id=\"43aacfe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b858580 elementor-widget elementor-widget-text-editor\" data-id=\"b858580\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"margin-top: 0cm;\"><span style=\"font-family: Ubuntu, sans-serif;\">Ellas son la nueva familia Lasierra, las cuatro Estrellas de esta nueva serie. Ahora tendr\u00e1n que dejar sus diferencias a un lado para sacar adelante el hotel.<\/span><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-bda6cae\" data-id=\"bda6cae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-41454a9 elementor-section-content-middle elementor-section-height-min-height elementor-hidden-tablet elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"41454a9\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[{&quot;_id&quot;:&quot;7bffb86&quot;,&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6ac3103\" data-id=\"6ac3103\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c253659 elementor-section-height-min-height elementor-section-content-top elementor-section-full_width elementor-section-height-default\" data-id=\"c253659\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;30d41bc&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3fe3cb7\" data-id=\"3fe3cb7\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c53c61 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0c53c61\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c6e6d52 elementor-section-full_width elementor-section-height-min-height elementor-section-content-bottom elementor-section-height-default\" data-id=\"c6e6d52\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;810e02d&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5791fe2\" data-id=\"5791fe2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51181b7 elementor-widget elementor-widget-text-editor\" data-id=\"51181b7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Complete <br \/>information <br \/>on the series<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-babc5ad\" data-id=\"babc5ad\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6161500 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"6161500\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-down\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<nav class=\"elementor-section elementor-inner-section elementor-element elementor-element-9434548 elementor-section-full_width elementor-section-height-min-height elementor-section-content-middle elementor-section-height-default\" data-id=\"9434548\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;735cce3&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-77a5202\" data-id=\"77a5202\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b03f74 elementor-widget elementor-widget-jet-mega-menu\" data-id=\"9b03f74\" data-element_type=\"widget\" data-widget_type=\"jet-mega-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"menu-jet-menu-4-estrellas-container\"><div class=\"jet-menu-container\"><div class=\"jet-menu-inner\"><ul class=\"jet-menu jet-menu--animation-type-none\"><li id=\"jet-menu-item-8623\" class=\"jet-menu-item jet-menu-item-type-custom jet-menu-item-object-custom jet-no-roll-up jet-mega-menu-item jet-regular-item jet-menu-item-has-children jet-menu-item-8623\"><a href=\"#\" class=\"top-level-link\"><div class=\"jet-menu-item-wrapper\"><div class=\"jet-menu-title\">1 Temporada<\/div><i class=\"jet-dropdown-arrow fa fa-angle-down\"><\/i><\/div><\/a><div class=\"jet-sub-mega-menu\" data-template-id=\"8627\">\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8627\" class=\"elementor elementor-8627\" data-elementor-post-type=\"jet-menu\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e75fc08 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e75fc08\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;e7d68da&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ec5081d\" data-id=\"ec5081d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bb16562 elementor-widget elementor-widget-heading\" data-id=\"bb16562\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">INFO<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff56eec elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ff56eec\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-422c1c8 elementor-widget elementor-widget-text-editor\" data-id=\"422c1c8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"margin-top: 0cm;\"><span style=\"color: #ffffff;\"><strong><span style=\"font-family: Ubuntu, sans-serif;\">Clara (Toni Acosta)<\/span><\/strong><span style=\"font-family: Ubuntu, sans-serif;\">, una antigua amiga de la infancia, ha vuelto con un secreto bajo el brazo\u2026\u00a0<em><span style=\"font-family: 'Ubuntu',sans-serif;\">\u201cYo tambi\u00e9n soy parte de esta familia. Yo tambi\u00e9n soy una Lasierra<\/span><\/em>\u201d.\u00a0<strong><span style=\"font-family: 'Ubuntu',sans-serif;\">Rita (Ana Gracia)<\/span><\/strong>\u00a0una madre demasiado preocupada por las apariencias, va a tirarse de los pelos con la noticia.\u00a0<strong><span style=\"font-family: 'Ubuntu',sans-serif;\">Marta (Dafne Fern\u00e1ndez),<\/span><\/strong>\u00a0caprichosa y superficial, va a declararle la guerra desde el minuto uno. Y\u00a0<strong><span style=\"font-family: 'Ubuntu',sans-serif;\">Silvia (Marta Aledo)<\/span><\/strong>, la bendita Silvia,<strong><span style=\"font-family: 'Ubuntu',sans-serif;\">\u00a0<\/span><\/strong>har\u00e1 todo lo posible porque la situaci\u00f3n no se vaya de madre.<\/span><\/span><\/p><p><span style=\"font-family: Ubuntu, sans-serif; color: #ffffff;\">Ellas son la nueva familia Lasierra, las cuatro Estrellas de esta nueva serie. Ahora tendr\u00e1n que dejar sus diferencias a un lado para sacar adelante el hotel.\u00a0 \u00bfSer\u00e1n capaces de hacerlo?<\/span><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-eaadfdc\" data-id=\"eaadfdc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a162cd4 elementor-widget elementor-widget-heading\" data-id=\"a162cd4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">TRAILER<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-428cc77 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"428cc77\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c4bcf5 elementor-widget elementor-widget-video\" data-id=\"8c4bcf5\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=xPHcxcZKIKA&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40af505 elementor-widget elementor-widget-heading\" data-id=\"40af505\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">4 Estrellas - Estreno de la primera temporada<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e9d06fd\" data-id=\"e9d06fd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10332d3 elementor-widget elementor-widget-heading\" data-id=\"10332d3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">AVAILABLE ON<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39884dd elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"39884dd\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb54456 elementor-widget elementor-widget-image\" data-id=\"cb54456\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"200\" src=\"https:\/\/thegoodmood.com\/wp-content\/uploads\/2020\/01\/atresplayer.png\" class=\"attachment-large size-large wp-image-480\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/thegoodmood.com\/wp-content\/uploads\/2020\/01\/atresplayer.png 500w, https:\/\/thegoodmood.com\/wp-content\/uploads\/2020\/01\/atresplayer-300x120.png 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a8b0fe elementor-widget elementor-widget-jet-accordion\" data-id=\"3a8b0fe\" data-element_type=\"widget\" data-widget_type=\"jet-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-accordion\" data-settings=\"{&quot;collapsible&quot;:false,&quot;ajaxTemplate&quot;:false,&quot;switchScrolling&quot;:false,&quot;switchScrollingOffset&quot;:0,&quot;switchScrollingDelay&quot;:500}\" role=\"tablist\">\n\t\t\t<div class=\"jet-accordion__inner\">\n\t\t\t\t<div class=\"jet-accordion__item jet-toggle jet-toggle-move-up-effect\">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-6131\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"jet-toggle-content-6131\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-arrow-circle-down\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">CREDITS<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-6131\" class=\"jet-toggle__content\" data-toggle=\"1\" role=\"tabpanel\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p><strong>Executive Producer<\/strong> Daniel \u00c9cija<\/p><p><strong>Productor\u00a0 Ejecutivo Good Mood:<\/strong> Javier Lorenzo<\/p><p><strong>Productora Ejecutiva<\/strong><\/p><p><strong>RTVE:<\/strong> Mar D\u00edaz<\/p><p><strong>Direcci\u00f3n\u00a0Argumental:<\/strong> \u00c1ngel Turl\u00e1n<\/p><p><strong>Coordinador de escaletas:<\/strong> Tirso Conde<\/p><p><strong>Coordinador de di\u00e1logos:<\/strong>\u00a0Aitor Santos<\/p><hr \/><p><strong>Screenwriters:<\/strong><\/p><p>\u00c1ngel Turl\u00e1n, Tirso Conde, Aitor Santos, Maite P\u00e9rez, Mario Albelo, Paco de Campos, Juan Salvador, Denis L\u00f3pez, Diego Soto, David Mu\u00f1oz, Ana Boyero, Eva Baeza, Nuria Cabello, Bea Esos, \u00c1ngela Ob\u00f3n, Beatriz Arias,\u00a0Raquel Mart\u00edn,\u00a0Borja Glez. Santaolalla y\u00a0Diana Rojo<\/p><hr \/><p><strong>Coordinador general:<\/strong><br \/>Jota Franco<\/p><hr \/><p><strong>Directors:<\/strong><br \/>Manu G\u00f3mez, \u00c1lvaro Vicario, Laura Campos, Luis Arribas y Juan Gil<\/p><hr \/><p><strong>Directora de producci\u00f3n: <\/strong>Sandra Melchor<\/p><hr \/><p><strong>Casting directors:<\/strong><br \/>Ana Sainz-Tr\u00e1paga y Patricia \u00c1lvarez de Miranda<\/p><hr \/><p><strong>Direcci\u00f3n de fotograf\u00eda:<\/strong><br \/>Fernando L\u00f3pez Coloma y Paco P\u00e9rez<\/p><hr \/><p><strong>Decoradora:<\/strong><br \/>Alicia Larrey<\/p><hr \/><p><strong>Figurinista:<\/strong><br \/>Gualter de S\u00e1<\/p><hr \/><p><strong>Art Direction: <\/strong>Marcelo Pacheco<\/p><hr \/><p><strong>Dise\u00f1o de maquillaje y peluquer\u00eda: <\/strong>Ana Ram\u00edrez y Juli\u00e1n Fern\u00e1ndez<\/p><hr \/><p><strong>Jefes sonido: <\/strong>Fonsi Gil y Nestor Luz<\/p><hr \/><p><strong>Montadores: <\/strong>Luis Terr\u00f3n, Silvia Pizarro y Paco Diaz<\/p><hr \/><p><strong>M\u00fasico: <\/strong>Jeansy<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div><\/li>\n<\/ul><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/nav>\n\t\t\t\t<div class=\"elementor-element elementor-element-8427403 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8427403\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c3762e1 elementor-section-full_width elementor-section-height-min-height elementor-section-content-bottom elementor-section-height-default\" data-id=\"c3762e1\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;810e02d&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1f0709b\" data-id=\"1f0709b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e69970 elementor-widget elementor-widget-text-editor\" data-id=\"2e69970\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Gallery<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-11aded1\" data-id=\"11aded1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c29daa elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"6c29daa\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-down\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0cf95bc elementor-section-full_width elementor-section-height-min-height elementor-section-content-bottom elementor-section-height-default\" data-id=\"0cf95bc\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;810e02d&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c85dd16\" data-id=\"c85dd16\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e5ea13 elementor-widget elementor-widget-gallery\" data-id=\"3e5ea13\" data-element_type=\"widget\" data-settings=\"{&quot;columns&quot;:3,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;content_hover_animation&quot;:&quot;grow&quot;,&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;columns_tablet&quot;:3,&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;lazyload&quot;:&quot;yes&quot;,&quot;gallery_layout&quot;:&quot;grid&quot;,&quot;columns_mobile&quot;:1,&quot;link_to&quot;:&quot;file&quot;,&quot;aspect_ratio&quot;:&quot;3:2&quot;,&quot;overlay_background&quot;:&quot;yes&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/thegoodmood.com\/wp-content\/uploads\/2023\/03\/Unknown-3-scaled.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3e5ea13\" data-elementor-lightbox-title=\"Unknown-3\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODYxOSwidXJsIjoiaHR0cHM6XC9cL3RoZWdvb2Rtb29kLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDNcL1Vua25vd24tMy1zY2FsZWQuanBlZyIsInNsaWRlc2hvdyI6IjNlNWVhMTMifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/thegoodmood.com\/wp-content\/uploads\/2023\/03\/Unknown-3-scaled.jpeg\" data-width=\"2560\" data-height=\"1730\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/thegoodmood.com\/wp-content\/uploads\/2023\/03\/4estrellas_web.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3e5ea13\" data-elementor-lightbox-title=\"4estrellas_web\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODYxOCwidXJsIjoiaHR0cHM6XC9cL3RoZWdvb2Rtb29kLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDNcLzRlc3RyZWxsYXNfd2ViLmpwZyIsInNsaWRlc2hvdyI6IjNlNWVhMTMifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/thegoodmood.com\/wp-content\/uploads\/2023\/03\/4estrellas_web.jpg\" data-width=\"1920\" data-height=\"1155\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7cf265b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7cf265b\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;8bbd491&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1d0d80e\" data-id=\"1d0d80e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-715f5a2 elementor-widget elementor-widget-text-editor\" data-id=\"715f5a2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Good news<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d41ae5a\" data-id=\"d41ae5a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9e476dd elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"9e476dd\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-down\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a8c081e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"a8c081e\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;c5f1e1e&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7accd1e\" data-id=\"7accd1e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b7569be elementor-widget elementor-widget-global elementor-global-3572 elementor-widget-jet-blog-smart-tiles\" data-id=\"b7569be\" data-element_type=\"widget\" data-widget_type=\"jet-blog-smart-tiles.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-jet-blog-smart-tiles jet-blog\"><div class=\"jet-smart-tiles-wrap jet-hide-excerpt\" data-slider-atts='{\"adaptiveHeight\":true,\"arrows\":false,\"prevArrow\":\"<i class=\\\"jet-arrow-prev jet-blog-arrow\\\"><svg width=\\\"24\\\" height=\\\"24\\\" viewBox=\\\"0 0 24 24\\\" fill=\\\"none\\\" xmlns=\\\"http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\\"><path d=\\\"M14.625 5.3999L16.3 7.0749L11.35 12.0249L16.3 16.9749L14.625 18.6499L7.99999 12.0249L14.625 5.3999Z\\\" fill=\\\"#0F172A\\\"\\\/><\\\/svg><\\\/i>\",\"nextArrow\":\"<i class=\\\"jet-arrow-next jet-blog-arrow\\\"><svg width=\\\"24\\\" height=\\\"24\\\" viewBox=\\\"0 0 24 24\\\" fill=\\\"none\\\" xmlns=\\\"http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\\"><path d=\\\"M9.37501 18.6001L7.70001 16.9251L12.65 11.9751L7.70001 7.0251L9.37501 5.3501L16 11.9751L9.37501 18.6001Z\\\" fill=\\\"#0F172A\\\"\\\/><\\\/svg><\\\/i>\",\"autoplay\":false,\"autoplaySpeed\":5000,\"rtl\":false}' dir=\"ltr\"><div class=\"jet-smart-tiles-slide\"><div class=\"jet-smart-tiles-slide__wrap layout-2-3-v\"><div class=\"jet-smart-tiles\">\n\t<div class=\"jet-smart-tiles__box\" style=\"background-image:url('https:\/\/thegoodmood.com\/wp-content\/uploads\/2026\/07\/LDDN_DSC03948_matiasuris-1024x683.jpg')\">\n\t\t<div class=\"jet-smart-tiles__terms\"><a href=\"https:\/\/thegoodmood.com\/eng\/tag\/good-mood\/\" class=\"jet-smart-tiles__terms-link jet-smart-tiles__terms-link--20\">good mood<\/a><\/div>\t\t<div class=\"jet-smart-tiles__box-content\">\n\t\t\t<div class=\"jet-smart-tiles__box-content-inner\">\n\t\t\t\t<div class=\"jet-smart-tiles__meta\"><\/div>\t\t\t\t\t\t\t\t<div class=\"jet-smart-tiles__box-title\">Comienza el rodaje de La dama del norte<\/div>\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"jet-smart-tiles__box-excerpt\">Netflix ha comenzado el rodaje de La Dama del Norte, su nueva serie creada por Daniel \u00c9cija (Los hombres de Paco, Vis a Vis) y...<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<a href=\"https:\/\/thegoodmood.com\/eng\/comienza-el-rodaje-de-la-dama-del-norte\/\" class=\"jet-smart-tiles__box-link\" aria-label=\"Comienza el rodaje de La dama del norte\"><\/a>\n\t<\/div>\n<\/div><div class=\"jet-smart-tiles\">\n\t<div class=\"jet-smart-tiles__box\" style=\"background-image:url('https:\/\/thegoodmood.com\/wp-content\/uploads\/2026\/04\/Rojosobreblanco_FotosElenco-61-1024x683.jpg')\">\n\t\t<div class=\"jet-smart-tiles__terms\"><a href=\"https:\/\/thegoodmood.com\/eng\/tag\/good-mood\/\" class=\"jet-smart-tiles__terms-link jet-smart-tiles__terms-link--20\">good mood<\/a><\/div>\t\t<div class=\"jet-smart-tiles__box-content\">\n\t\t\t<div class=\"jet-smart-tiles__box-content-inner\">\n\t\t\t\t<div class=\"jet-smart-tiles__meta\"><\/div>\t\t\t\t\t\t\t\t<div class=\"jet-smart-tiles__box-title\">RTVE rueda la nueva serie polic\u00edaca &#8216;Rojo sobre blanco&#8217;, con Hugo Silva y Mar\u00eda Herv\u00e1s<\/div>\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"jet-smart-tiles__box-excerpt\">RTVE rueda la nueva serie polic\u00edaca 'Rojo sobre blanco', con Hugo Silva y Mar\u00eda Herv\u00e1s Completan el reparto Irene Arcos, Pablo Derqui, Manu Baqueiro, Francis...<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<a href=\"https:\/\/thegoodmood.com\/eng\/rtve-rueda-la-nueva-serie-policiaca-rojo-sobre-blanco-con-hugo-silva-y-maria-hervas\/\" class=\"jet-smart-tiles__box-link\" aria-label=\"RTVE rueda la nueva serie polic\u00edaca &#8216;Rojo sobre blanco&#8217;, con Hugo Silva y Mar\u00eda Herv\u00e1s\"><\/a>\n\t<\/div>\n<\/div><div class=\"jet-smart-tiles\">\n\t<div class=\"jet-smart-tiles__box\" style=\"background-image:url('https:\/\/thegoodmood.com\/wp-content\/uploads\/2025\/12\/08_07_01_B_0044C003_231031_132319_h1E52.mxf_1.3.5-1024x503.jpg')\">\n\t\t<div class=\"jet-smart-tiles__terms\"><a href=\"https:\/\/thegoodmood.com\/eng\/tag\/evanicole\/\" class=\"jet-smart-tiles__terms-link jet-smart-tiles__terms-link--41\">Eva&amp;nicole<\/a><\/div>\t\t<div class=\"jet-smart-tiles__box-content\">\n\t\t\t<div class=\"jet-smart-tiles__box-content-inner\">\n\t\t\t\t<div class=\"jet-smart-tiles__meta\"><\/div>\t\t\t\t\t\t\t\t<div class=\"jet-smart-tiles__box-title\">\u2018RENATA &amp; NICOLE\u2019 (NUEVA SERIE)<\/div>\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"jet-smart-tiles__box-excerpt\">Tras el \u00e9xito de la primera temporada, el universo del lujo de la Marbella de los 80 regresa con el protagonismo de dos amigas \u2018Renata...<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<a href=\"https:\/\/thegoodmood.com\/eng\/renata-nicole-nueva-serie\/\" class=\"jet-smart-tiles__box-link\" aria-label=\"\u2018RENATA &amp; NICOLE\u2019 (NUEVA SERIE)\"><\/a>\n\t<\/div>\n<\/div><div class=\"jet-smart-tiles\">\n\t<div class=\"jet-smart-tiles__box\" style=\"background-image:url('https:\/\/thegoodmood.com\/wp-content\/uploads\/2025\/09\/LA-AGENCIA-HORIZONTAL-1024x717.jpg')\">\n\t\t<div class=\"jet-smart-tiles__terms\"><a href=\"https:\/\/thegoodmood.com\/eng\/tag\/good-mood\/\" class=\"jet-smart-tiles__terms-link jet-smart-tiles__terms-link--20\">good mood<\/a><\/div>\t\t<div class=\"jet-smart-tiles__box-content\">\n\t\t\t<div class=\"jet-smart-tiles__box-content-inner\">\n\t\t\t\t<div class=\"jet-smart-tiles__meta\"><\/div>\t\t\t\t\t\t\t\t<div class=\"jet-smart-tiles__box-title\">Mediaset Espa\u00f1a presenta en el FesTVal \u2018La Agencia\u2019, una de las principales apuestas de ficci\u00f3n de Telecinco para la nueva temporada<\/div>\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"jet-smart-tiles__box-excerpt\">El estreno ser\u00e1 el pr\u00f3ximo mi\u00e9rcoles 10 de septiembre a las 23:00h.&nbsp; Esta tarde tendr\u00e1 lugar en Vitoria el preestreno en exclusiva del primer cap\u00edtulo,...<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<a href=\"https:\/\/thegoodmood.com\/eng\/mediaset-espana-presenta-en-el-festval-la-agencia-una-de-las-principales-apuestas-de-ficcion-de-telecinco-para-la-nueva-temporada\/\" class=\"jet-smart-tiles__box-link\" aria-label=\"Mediaset Espa\u00f1a presenta en el FesTVal \u2018La Agencia\u2019, una de las principales apuestas de ficci\u00f3n de Telecinco para la nueva temporada\"><\/a>\n\t<\/div>\n<\/div><div class=\"jet-smart-tiles\">\n\t<div class=\"jet-smart-tiles__box\" style=\"background-image:url('https:\/\/thegoodmood.com\/wp-content\/uploads\/2025\/04\/EVANICOLE_PPAL_HORIZONTAL_GRUPAL-1024x724.jpg')\">\n\t\t<div class=\"jet-smart-tiles__terms\"><a href=\"https:\/\/thegoodmood.com\/eng\/tag\/evanicole\/\" class=\"jet-smart-tiles__terms-link jet-smart-tiles__terms-link--41\">Eva&amp;nicole<\/a><\/div>\t\t<div class=\"jet-smart-tiles__box-content\">\n\t\t\t<div class=\"jet-smart-tiles__box-content-inner\">\n\t\t\t\t<div class=\"jet-smart-tiles__meta\"><\/div>\t\t\t\t\t\t\t\t<div class=\"jet-smart-tiles__box-title\">Antena 3 estrena el pr\u00f3ximo jueves, 8 de mayo, \u2018Eva &amp; Nicole\u2019, su nueva serie protagonizada por Bel\u00e9n Rueda e Hiba Abouk<\/div>\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"jet-smart-tiles__box-excerpt\">Lujo, poder y venganza se dar\u00e1n cita en el Prime Time de Antena 3 desde el pr\u00f3ximo jueves, 8 de mayo, con \u2018Eva &amp; Nicole\u2019,...<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<a href=\"https:\/\/thegoodmood.com\/eng\/antena-3-estrena-el-proximo-jueves-8-de-mayo-eva-nicole-su-nueva-serie-protagonizada-por-belen-rueda-e-hiba-abouk\/\" class=\"jet-smart-tiles__box-link\" aria-label=\"Antena 3 estrena el pr\u00f3ximo jueves, 8 de mayo, \u2018Eva &amp; Nicole\u2019, su nueva serie protagonizada por Bel\u00e9n Rueda e Hiba Abouk\"><\/a>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c3bc757 elementor-section-content-middle elementor-section-height-min-height elementor-hidden-desktop elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"c3bc757\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[{&quot;_id&quot;:&quot;7bffb86&quot;,&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-de5a25b\" data-id=\"de5a25b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cc3851a elementor-section-height-min-height elementor-section-content-top elementor-section-full_width elementor-section-height-default\" data-id=\"cc3851a\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;30d41bc&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-09fcba3\" data-id=\"09fcba3\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0bd84b9 elementor-widget elementor-widget-text-editor\" data-id=\"0bd84b9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>4<\/p><p>Estrellas<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-777352e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"777352e\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4a8f226 elementor-section-full_width elementor-section-height-min-height elementor-section-content-bottom elementor-section-height-default\" data-id=\"4a8f226\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;810e02d&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e1ad37b\" data-id=\"e1ad37b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a61a56 elementor-widget elementor-widget-text-editor\" data-id=\"1a61a56\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Complete <br \/>information <br \/>on the series<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0f2be9e\" data-id=\"0f2be9e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf1293b elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"cf1293b\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-down\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<nav class=\"elementor-section elementor-inner-section elementor-element elementor-element-a500aef elementor-section-full_width elementor-section-content-middle elementor-hidden-desktop elementor-section-height-default elementor-section-height-default\" data-id=\"a500aef\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;735cce3&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-90383ef\" data-id=\"90383ef\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2563533 elementor-widget elementor-widget-jet-hamburger-panel\" data-id=\"2563533\" data-element_type=\"widget\" data-widget_type=\"jet-hamburger-panel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-hamburger-panel jet-hamburger-panel-right-position jet-hamburger-panel-slide-effect\" data-settings=\"{&quot;position&quot;:&quot;right&quot;,&quot;ajaxTemplate&quot;:false,&quot;ajaxTemplateCache&quot;:true}\">\n\t\t\t<div class=\"jet-hamburger-panel__toggle\" role=\"button\" tabindex=\"0\"><div class=\"jet-hamburger-panel__toggle-icon\"><span class=\"jet-hamburger-panel__icon icon-normal jet-blocks-icon\"><i aria-hidden=\"true\" class=\"fas fa-align-justify\"><\/i><\/span><span class=\"jet-hamburger-panel__icon icon-active jet-blocks-icon\"><i aria-hidden=\"true\" class=\"fas fa-times\"><\/i><\/span><\/div><div class=\"jet-hamburger-panel__toggle-label\"><span>SEASON 1<\/span><\/div><\/div>\t\t\t<div class=\"jet-hamburger-panel__instance\">\n\t\t\t\t<div class=\"jet-hamburger-panel__cover\"><\/div>\n\t\t\t\t<div class=\"jet-hamburger-panel__inner\">\n\t\t\t\t\t<div class=\"jet-hamburger-panel__close-button jet-blocks-icon\"><i aria-hidden=\"true\" class=\"fas fa-times\"><\/i><\/div><div class=\"jet-hamburger-panel__content\" data-template-id=\"8412\">\t\t<div data-elementor-type=\"page\" data-elementor-id=\"8412\" class=\"elementor elementor-8412\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1dd54bc elementor-section-full_width animated-slow elementor-section-height-default elementor-section-height-default\" data-id=\"1dd54bc\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;e60a7d2&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}],&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-588ed00\" data-id=\"588ed00\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-aef23fd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aef23fd\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;1be264d&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7c39c31\" data-id=\"7c39c31\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a4e652e elementor-widget elementor-widget-heading\" data-id=\"a4e652e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">INFO<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad6a48e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ad6a48e\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-beb59f6 elementor-widget elementor-widget-text-editor\" data-id=\"beb59f6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Madrid, 1979. \u00c1ngel Cristo es el mejor domador del mundo. B\u00e1rbara Rey, actriz y musa del destape, la mujer m\u00e1s deseada de Espa\u00f1a. Desde que se conocen hasta que anuncian su matrimonio transcurren s\u00f3lo unas semanas. Es la boda del a\u00f1o y la noticia copa las portadas de todas las revistas. El Circo de B\u00e1rbara Rey y \u00c1ngel Cristo se convierte en el espect\u00e1culo de moda; un negocio millonario.<\/p><p>Dinero, fama, lujo\u2026 Nueve a\u00f1os de relaci\u00f3n en los que Espa\u00f1a fue testigo de la felicidad de la pareja: el nacimiento de Angelito y Sof\u00eda, la compra de coches deportivos, joyas, un ostentoso chalet en La Moraleja\u2026 Lejos de los flashes, sin embargo, se esconde una escalada de drogadicci\u00f3n, ludopat\u00eda, infidelidades y malos tratos\u2026<\/p><p>Y, de fondo, la sombra de la relaci\u00f3n de B\u00e1rbara con un poderoso hombre de estado\u2026<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d85feec elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d85feec\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;1be264d&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-385d37c\" data-id=\"385d37c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bdd154b elementor-widget elementor-widget-heading\" data-id=\"bdd154b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">TRAILER<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ad2ef3 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1ad2ef3\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-905c466 elementor-widget elementor-widget-video\" data-id=\"905c466\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/ea91NXS00_A&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/thegoodmood.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/CRISTO-Y-REY_A3_Atresplayer_Good-Mood_web1.jpg&quot;,&quot;id&quot;:8213,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;lightbox&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-lightbox\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox=\"{&quot;type&quot;:&quot;video&quot;,&quot;videoType&quot;:&quot;youtube&quot;,&quot;url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/embed\\\/ea91NXS00_A?feature=oembed&amp;start&amp;end&amp;wmode=opaque&amp;loop=0&amp;controls=1&amp;mute=0&amp;rel=0&amp;modestbranding=0&quot;,&quot;modalOptions&quot;:{&quot;id&quot;:&quot;elementor-lightbox-905c466&quot;,&quot;entranceAnimation&quot;:&quot;&quot;,&quot;entranceAnimation_tablet&quot;:&quot;&quot;,&quot;entranceAnimation_mobile&quot;:&quot;&quot;,&quot;videoAspectRatio&quot;:&quot;169&quot;}}\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJ0eXBlIjoidmlkZW8iLCJ2aWRlb1R5cGUiOiJ5b3V0dWJlIiwidXJsIjoiaHR0cHM6XC9cL3d3dy55b3V0dWJlLmNvbVwvZW1iZWRcL2VhOTFOWFMwMF9BP2ZlYXR1cmU9b2VtYmVkJnN0YXJ0JmVuZCZ3bW9kZT1vcGFxdWUmbG9vcD0wJmNvbnRyb2xzPTEmbXV0ZT0wJnJlbD0wJm1vZGVzdGJyYW5kaW5nPTAiLCJtb2RhbE9wdGlvbnMiOnsiaWQiOiJlbGVtZW50b3ItbGlnaHRib3gtOTA1YzQ2NiIsImVudHJhbmNlQW5pbWF0aW9uIjoiIiwiZW50cmFuY2VBbmltYXRpb25fdGFibGV0IjoiIiwiZW50cmFuY2VBbmltYXRpb25fbW9iaWxlIjoiIiwidmlkZW9Bc3BlY3RSYXRpbyI6IjE2OSJ9fQ%3D%3D\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/thegoodmood.com\/wp-content\/uploads\/2022\/05\/CRISTO-Y-REY_A3_Atresplayer_Good-Mood_web1.jpg\" class=\"attachment-full size-full wp-image-8213\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/thegoodmood.com\/wp-content\/uploads\/2022\/05\/CRISTO-Y-REY_A3_Atresplayer_Good-Mood_web1.jpg 1920w, https:\/\/thegoodmood.com\/wp-content\/uploads\/2022\/05\/CRISTO-Y-REY_A3_Atresplayer_Good-Mood_web1-300x200.jpg 300w, https:\/\/thegoodmood.com\/wp-content\/uploads\/2022\/05\/CRISTO-Y-REY_A3_Atresplayer_Good-Mood_web1-1024x683.jpg 1024w, https:\/\/thegoodmood.com\/wp-content\/uploads\/2022\/05\/CRISTO-Y-REY_A3_Atresplayer_Good-Mood_web1-768x512.jpg 768w, https:\/\/thegoodmood.com\/wp-content\/uploads\/2022\/05\/CRISTO-Y-REY_A3_Atresplayer_Good-Mood_web1-1536x1024.jpg 1536w, https:\/\/thegoodmood.com\/wp-content\/uploads\/2022\/05\/CRISTO-Y-REY_A3_Atresplayer_Good-Mood_web1-18x12.jpg 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"Play Video\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Play Video<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd8708e elementor-widget elementor-widget-heading\" data-id=\"fd8708e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Cristo y Rey - Estreno de la primera temporada<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-370f995 elementor-widget elementor-widget-spacer\" data-id=\"370f995\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-838325c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"838325c\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;1be264d&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6fa1d73\" data-id=\"6fa1d73\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b930a2a elementor-widget elementor-widget-heading\" data-id=\"b930a2a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">AVAILABLE ON<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d2794b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8d2794b\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4968d8 elementor-widget elementor-widget-image\" data-id=\"e4968d8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.atresplayer.com\/antena3\/series\/la-valla\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/thegoodmood.com\/wp-content\/uploads\/elementor\/thumbs\/atresplayer-okcla2u1egfzh6x345xs10hgj9cjgo1ba4erpvb97s.png\" title=\"atresplayer\" alt=\"atresplayer\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2e7eb9 elementor-widget elementor-widget-jet-accordion\" data-id=\"d2e7eb9\" data-element_type=\"widget\" data-widget_type=\"jet-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-accordion\" data-settings=\"{&quot;collapsible&quot;:false,&quot;ajaxTemplate&quot;:false,&quot;switchScrolling&quot;:false,&quot;switchScrollingOffset&quot;:0,&quot;switchScrollingDelay&quot;:500}\" role=\"tablist\">\n\t\t\t<div class=\"jet-accordion__inner\">\n\t\t\t\t<div class=\"jet-accordion__item jet-toggle jet-toggle-move-up-effect\">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-2211\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"jet-toggle-content-2211\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-arrow-down\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-arrow-up\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">CREDITS<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-2211\" class=\"jet-toggle__content\" data-toggle=\"1\" role=\"tabpanel\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p><strong>Creador\/Showrunner:\u00a0<\/strong>Daniel \u00c9cija<\/p><p><strong>Producci\u00f3n ejecutiva:\u00a0<\/strong>Montse Garc\u00eda y Daniel \u00c9cija<\/p><hr \/><p><strong>Screenwriters:<\/strong><br \/>Daniel E\u0301cija, Andre\u0301s Marti\u0301n Soto, Patricia Trueba, Ce\u0301sar Mendiza\u0301bal, I\u00f1aki San Rom\u00e1n, A\u0301ngel Gasco-Coloma<\/p><hr \/><p><strong>Directors:<\/strong><br \/>David Molina<br \/>Manu G\u00f3mez<\/p><hr \/><p><strong>Casting directors:<\/strong><br \/>Luis San Narciso<br \/>Tonucha Vidal<\/p><hr \/><p><strong>Design DP:<\/strong><br \/>N\u00e9stor Calvo<br \/>Paco Belda<\/p><hr \/><p><strong>Music:<\/strong><br \/>Daniel S\u00e1nchez de la Hera<\/p><hr \/><p><strong>Production Management:<\/strong><br \/>Salvador G\u00f3mez<\/p><hr \/><p><strong>Casting directors: <\/strong>Ana Sainz-Tr\u00e1paga y Patricia \u00c1lvarez de Miranda<\/p><hr \/><p><strong>DP:\u00a0<\/strong>Tommie Ferreras AEC,\u00a02\u00ba unidad: Ismael Issa<\/p><hr \/><p><strong>Art Direction: <\/strong>Koldo Vall\u00e9s<\/p><hr \/><p><strong>Dise\u00f1o Vestuario:\u00a0<\/strong>Loles Garc\u00eda\u00a0<\/p><hr \/><p><strong>Dise\u00f1o de maquillaje y vestuario:\u00a0<\/strong>Romana Gonz\u00e1lez \u2018Pato\u2019 y Antonio Panizza<\/p><hr \/><p><strong>Sonido:\u00a0<\/strong>N\u00e9stor Luz<\/p><hr \/><p><strong>Montador \/ Editor:\u00a0<\/strong>Fernando M\u00e1rquez<\/p><hr \/><p><strong>Efectos Especiales (VFX):\u00a0<\/strong>Jordi San Agust\u00edn y \u00c1lvaro Vicario<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/nav>\n\t\t\t\t<div class=\"elementor-element elementor-element-98f4c81 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"98f4c81\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5fcaec0 elementor-section-full_width elementor-section-height-min-height elementor-section-content-bottom elementor-section-height-default\" data-id=\"5fcaec0\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;810e02d&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c435540\" data-id=\"c435540\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f9e2d6 elementor-widget elementor-widget-text-editor\" data-id=\"2f9e2d6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Gallery<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ea316e0\" data-id=\"ea316e0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-321d57e elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"321d57e\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-down\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-dcd8706\" data-id=\"dcd8706\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fdf46e1 elementor-widget elementor-widget-gallery\" data-id=\"fdf46e1\" data-element_type=\"widget\" data-settings=\"{&quot;columns&quot;:3,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;content_hover_animation&quot;:&quot;grow&quot;,&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;columns_tablet&quot;:3,&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;lazyload&quot;:&quot;yes&quot;,&quot;gallery_layout&quot;:&quot;grid&quot;,&quot;columns_mobile&quot;:1,&quot;link_to&quot;:&quot;file&quot;,&quot;aspect_ratio&quot;:&quot;3:2&quot;,&quot;overlay_background&quot;:&quot;yes&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/thegoodmood.com\/wp-content\/uploads\/2023\/03\/Unknown-3-scaled.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"fdf46e1\" data-elementor-lightbox-title=\"Unknown-3\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODYxOSwidXJsIjoiaHR0cHM6XC9cL3RoZWdvb2Rtb29kLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDNcL1Vua25vd24tMy1zY2FsZWQuanBlZyIsInNsaWRlc2hvdyI6ImZkZjQ2ZTEifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/thegoodmood.com\/wp-content\/uploads\/2023\/03\/Unknown-3-scaled.jpeg\" data-width=\"2560\" data-height=\"1730\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/thegoodmood.com\/wp-content\/uploads\/2023\/03\/4estrellas_web.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"fdf46e1\" data-elementor-lightbox-title=\"4estrellas_web\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODYxOCwidXJsIjoiaHR0cHM6XC9cL3RoZWdvb2Rtb29kLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDNcLzRlc3RyZWxsYXNfd2ViLmpwZyIsInNsaWRlc2hvdyI6ImZkZjQ2ZTEifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/thegoodmood.com\/wp-content\/uploads\/2023\/03\/4estrellas_web.jpg\" data-width=\"1920\" data-height=\"1155\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b027bb0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b027bb0\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;8bbd491&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ec1920a\" data-id=\"ec1920a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf85e52 elementor-widget elementor-widget-text-editor\" data-id=\"cf85e52\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Good news<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2df7d01\" data-id=\"2df7d01\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c7f5f5b elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"c7f5f5b\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-down\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-0e42b35\" data-id=\"0e42b35\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b13b4ef elementor-widget elementor-widget-global elementor-global-3572 elementor-widget-jet-blog-smart-tiles\" data-id=\"b13b4ef\" data-element_type=\"widget\" data-widget_type=\"jet-blog-smart-tiles.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-jet-blog-smart-tiles jet-blog\"><div class=\"jet-smart-tiles-wrap jet-hide-excerpt\" data-slider-atts='{\"adaptiveHeight\":true,\"arrows\":false,\"prevArrow\":\"<i class=\\\"jet-arrow-prev jet-blog-arrow\\\"><svg width=\\\"24\\\" height=\\\"24\\\" viewBox=\\\"0 0 24 24\\\" fill=\\\"none\\\" xmlns=\\\"http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\\"><path d=\\\"M14.625 5.3999L16.3 7.0749L11.35 12.0249L16.3 16.9749L14.625 18.6499L7.99999 12.0249L14.625 5.3999Z\\\" fill=\\\"#0F172A\\\"\\\/><\\\/svg><\\\/i>\",\"nextArrow\":\"<i class=\\\"jet-arrow-next jet-blog-arrow\\\"><svg width=\\\"24\\\" height=\\\"24\\\" viewBox=\\\"0 0 24 24\\\" fill=\\\"none\\\" xmlns=\\\"http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\\"><path d=\\\"M9.37501 18.6001L7.70001 16.9251L12.65 11.9751L7.70001 7.0251L9.37501 5.3501L16 11.9751L9.37501 18.6001Z\\\" fill=\\\"#0F172A\\\"\\\/><\\\/svg><\\\/i>\",\"autoplay\":false,\"autoplaySpeed\":5000,\"rtl\":false}' dir=\"ltr\"><div class=\"jet-smart-tiles-slide\"><div class=\"jet-smart-tiles-slide__wrap layout-2-3-v\"><div class=\"jet-smart-tiles\">\n\t<div class=\"jet-smart-tiles__box\" style=\"background-image:url('https:\/\/thegoodmood.com\/wp-content\/uploads\/2026\/07\/LDDN_DSC03948_matiasuris-1024x683.jpg')\">\n\t\t<div class=\"jet-smart-tiles__terms\"><a href=\"https:\/\/thegoodmood.com\/eng\/tag\/good-mood\/\" class=\"jet-smart-tiles__terms-link jet-smart-tiles__terms-link--20\">good mood<\/a><\/div>\t\t<div class=\"jet-smart-tiles__box-content\">\n\t\t\t<div class=\"jet-smart-tiles__box-content-inner\">\n\t\t\t\t<div class=\"jet-smart-tiles__meta\"><\/div>\t\t\t\t\t\t\t\t<div class=\"jet-smart-tiles__box-title\">Comienza el rodaje de La dama del norte<\/div>\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"jet-smart-tiles__box-excerpt\">Netflix ha comenzado el rodaje de La Dama del Norte, su nueva serie creada por Daniel \u00c9cija (Los hombres de Paco, Vis a Vis) y...<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<a href=\"https:\/\/thegoodmood.com\/eng\/comienza-el-rodaje-de-la-dama-del-norte\/\" class=\"jet-smart-tiles__box-link\" aria-label=\"Comienza el rodaje de La dama del norte\"><\/a>\n\t<\/div>\n<\/div><div class=\"jet-smart-tiles\">\n\t<div class=\"jet-smart-tiles__box\" style=\"background-image:url('https:\/\/thegoodmood.com\/wp-content\/uploads\/2026\/04\/Rojosobreblanco_FotosElenco-61-1024x683.jpg')\">\n\t\t<div class=\"jet-smart-tiles__terms\"><a href=\"https:\/\/thegoodmood.com\/eng\/tag\/good-mood\/\" class=\"jet-smart-tiles__terms-link jet-smart-tiles__terms-link--20\">good mood<\/a><\/div>\t\t<div class=\"jet-smart-tiles__box-content\">\n\t\t\t<div class=\"jet-smart-tiles__box-content-inner\">\n\t\t\t\t<div class=\"jet-smart-tiles__meta\"><\/div>\t\t\t\t\t\t\t\t<div class=\"jet-smart-tiles__box-title\">RTVE rueda la nueva serie polic\u00edaca &#8216;Rojo sobre blanco&#8217;, con Hugo Silva y Mar\u00eda Herv\u00e1s<\/div>\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"jet-smart-tiles__box-excerpt\">RTVE rueda la nueva serie polic\u00edaca 'Rojo sobre blanco', con Hugo Silva y Mar\u00eda Herv\u00e1s Completan el reparto Irene Arcos, Pablo Derqui, Manu Baqueiro, Francis...<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<a href=\"https:\/\/thegoodmood.com\/eng\/rtve-rueda-la-nueva-serie-policiaca-rojo-sobre-blanco-con-hugo-silva-y-maria-hervas\/\" class=\"jet-smart-tiles__box-link\" aria-label=\"RTVE rueda la nueva serie polic\u00edaca &#8216;Rojo sobre blanco&#8217;, con Hugo Silva y Mar\u00eda Herv\u00e1s\"><\/a>\n\t<\/div>\n<\/div><div class=\"jet-smart-tiles\">\n\t<div class=\"jet-smart-tiles__box\" style=\"background-image:url('https:\/\/thegoodmood.com\/wp-content\/uploads\/2025\/12\/08_07_01_B_0044C003_231031_132319_h1E52.mxf_1.3.5-1024x503.jpg')\">\n\t\t<div class=\"jet-smart-tiles__terms\"><a href=\"https:\/\/thegoodmood.com\/eng\/tag\/evanicole\/\" class=\"jet-smart-tiles__terms-link jet-smart-tiles__terms-link--41\">Eva&amp;nicole<\/a><\/div>\t\t<div class=\"jet-smart-tiles__box-content\">\n\t\t\t<div class=\"jet-smart-tiles__box-content-inner\">\n\t\t\t\t<div class=\"jet-smart-tiles__meta\"><\/div>\t\t\t\t\t\t\t\t<div class=\"jet-smart-tiles__box-title\">\u2018RENATA &amp; NICOLE\u2019 (NUEVA SERIE)<\/div>\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"jet-smart-tiles__box-excerpt\">Tras el \u00e9xito de la primera temporada, el universo del lujo de la Marbella de los 80 regresa con el protagonismo de dos amigas \u2018Renata...<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<a href=\"https:\/\/thegoodmood.com\/eng\/renata-nicole-nueva-serie\/\" class=\"jet-smart-tiles__box-link\" aria-label=\"\u2018RENATA &amp; NICOLE\u2019 (NUEVA SERIE)\"><\/a>\n\t<\/div>\n<\/div><div class=\"jet-smart-tiles\">\n\t<div class=\"jet-smart-tiles__box\" style=\"background-image:url('https:\/\/thegoodmood.com\/wp-content\/uploads\/2025\/09\/LA-AGENCIA-HORIZONTAL-1024x717.jpg')\">\n\t\t<div class=\"jet-smart-tiles__terms\"><a href=\"https:\/\/thegoodmood.com\/eng\/tag\/good-mood\/\" class=\"jet-smart-tiles__terms-link jet-smart-tiles__terms-link--20\">good mood<\/a><\/div>\t\t<div class=\"jet-smart-tiles__box-content\">\n\t\t\t<div class=\"jet-smart-tiles__box-content-inner\">\n\t\t\t\t<div class=\"jet-smart-tiles__meta\"><\/div>\t\t\t\t\t\t\t\t<div class=\"jet-smart-tiles__box-title\">Mediaset Espa\u00f1a presenta en el FesTVal \u2018La Agencia\u2019, una de las principales apuestas de ficci\u00f3n de Telecinco para la nueva temporada<\/div>\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"jet-smart-tiles__box-excerpt\">El estreno ser\u00e1 el pr\u00f3ximo mi\u00e9rcoles 10 de septiembre a las 23:00h.&nbsp; Esta tarde tendr\u00e1 lugar en Vitoria el preestreno en exclusiva del primer cap\u00edtulo,...<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<a href=\"https:\/\/thegoodmood.com\/eng\/mediaset-espana-presenta-en-el-festval-la-agencia-una-de-las-principales-apuestas-de-ficcion-de-telecinco-para-la-nueva-temporada\/\" class=\"jet-smart-tiles__box-link\" aria-label=\"Mediaset Espa\u00f1a presenta en el FesTVal \u2018La Agencia\u2019, una de las principales apuestas de ficci\u00f3n de Telecinco para la nueva temporada\"><\/a>\n\t<\/div>\n<\/div><div class=\"jet-smart-tiles\">\n\t<div class=\"jet-smart-tiles__box\" style=\"background-image:url('https:\/\/thegoodmood.com\/wp-content\/uploads\/2025\/04\/EVANICOLE_PPAL_HORIZONTAL_GRUPAL-1024x724.jpg')\">\n\t\t<div class=\"jet-smart-tiles__terms\"><a href=\"https:\/\/thegoodmood.com\/eng\/tag\/evanicole\/\" class=\"jet-smart-tiles__terms-link jet-smart-tiles__terms-link--41\">Eva&amp;nicole<\/a><\/div>\t\t<div class=\"jet-smart-tiles__box-content\">\n\t\t\t<div class=\"jet-smart-tiles__box-content-inner\">\n\t\t\t\t<div class=\"jet-smart-tiles__meta\"><\/div>\t\t\t\t\t\t\t\t<div class=\"jet-smart-tiles__box-title\">Antena 3 estrena el pr\u00f3ximo jueves, 8 de mayo, \u2018Eva &amp; Nicole\u2019, su nueva serie protagonizada por Bel\u00e9n Rueda e Hiba Abouk<\/div>\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"jet-smart-tiles__box-excerpt\">Lujo, poder y venganza se dar\u00e1n cita en el Prime Time de Antena 3 desde el pr\u00f3ximo jueves, 8 de mayo, con \u2018Eva &amp; Nicole\u2019,...<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<a href=\"https:\/\/thegoodmood.com\/eng\/antena-3-estrena-el-proximo-jueves-8-de-mayo-eva-nicole-su-nueva-serie-protagonizada-por-belen-rueda-e-hiba-abouk\/\" class=\"jet-smart-tiles__box-link\" aria-label=\"Antena 3 estrena el pr\u00f3ximo jueves, 8 de mayo, \u2018Eva &amp; Nicole\u2019, su nueva serie protagonizada por Bel\u00e9n Rueda e Hiba Abouk\"><\/a>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Ellas son la nueva familia Lasierra, las cuatro Estrellas de esta nueva serie. Ahora tendr\u00e1n que dejar sus diferencias a un lado para sacar adelante el hotel. Toda la informaci\u00f3n sobre la serie 1 Temporada INFO Clara (Toni Acosta), una antigua amiga de la infancia, ha vuelto con un secreto bajo el brazo\u2026\u00a0\u201cYo tambi\u00e9n soy [&hellip;]<\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/thegoodmood.com\/eng\/wp-json\/wp\/v2\/pages\/8615"}],"collection":[{"href":"https:\/\/thegoodmood.com\/eng\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/thegoodmood.com\/eng\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/thegoodmood.com\/eng\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/thegoodmood.com\/eng\/wp-json\/wp\/v2\/comments?post=8615"}],"version-history":[{"count":27,"href":"https:\/\/thegoodmood.com\/eng\/wp-json\/wp\/v2\/pages\/8615\/revisions"}],"predecessor-version":[{"id":9144,"href":"https:\/\/thegoodmood.com\/eng\/wp-json\/wp\/v2\/pages\/8615\/revisions\/9144"}],"wp:attachment":[{"href":"https:\/\/thegoodmood.com\/eng\/wp-json\/wp\/v2\/media?parent=8615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}